{"id":3099,"date":"2017-08-22T17:42:10","date_gmt":"2017-08-22T16:42:10","guid":{"rendered":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/?p=3099"},"modified":"2017-08-28T16:01:00","modified_gmt":"2017-08-28T15:01:00","slug":"blue-mountains","status":"publish","type":"post","link":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/2017\/08\/22\/blue-mountains\/","title":{"rendered":"Blue mountains"},"content":{"rendered":"<p><b><br \/>\n<\/b><\/p>\n<p><b>Le montagne blue<\/b>\u00a0non sono blue cos\u00ec come i 12 apostoli non sono in realt\u00e0 12: i veri romanzi stanno scritti nelle guide turistiche, ne sono ormai certo.\u00a0<b>Il mostro che dentro ci ha divorato nella lenta Sydney ci ha spinto a lasciarla in fretta per via di quelle riflessioni che giorni fa abbiamo fatto bevendo un caff\u00e8, rifiatando dai tanti km camminati, a riguardo di citt\u00e0 e costruzione di queste, di \u201curbanistica\u201d e vivibilit\u00e0.\u00a0<\/b><\/p>\n<p><!--more--><\/p>\n<p>Il nostro viaggio verso <b>Katoomba<\/b> \u00e8 stato veloce con l\u2019ennesima auto presa a noleggio ed intervallata da soste provviste pi\u00f9 o meno salutari (confesso, biscotti al cioccolato e twix oltre frutta secca tostata ma non salata) e mezzi di litri di caff\u00e8 da bere rischiando le papille gustative.<\/p>\n<p>Katoomba \u00e8 montagna vera, <b>temperature che tornano ad essere invernali<\/b>: un piccolo centro piuttosto ricettivo che con <b>Leura<\/b> forma una coppia di cittadelle dove poter alloggiare e dalle quali poter partire per i numerosi percorsi di trekking che da li si dipanano. Il piccolo centro informazioni sul punto panoramico fornisce qualche carta e qualche informazione utile ma in nessun caso mi sento di definire utile il loro servizio n\u00e9 la loro carta a pagamento da 6 dollari. \u00a0Di base c\u2019\u00e8 da capire che lungo la strada che collega i due centri abitati, fra le parecchie curve ben asfaltate, corrono percorsi che vanno verso punti panoramici o cascate: va detto che in alcuni casi intravedere asfalto o sentire rumori di automobili a nemmeno 10 metri da dove si cammina non \u00e8 n\u00e9 eccitante n\u00e9 sicuro e fa perdere un bel po&#8217; di quel senso di avventura e natura che il trekking generalmente regala. Qui per\u00f2 le cose sono organizzate in questo modo ed in alcuni passaggi, anche a causa della manutenzione dei percorsi, si esce proprio sull\u2019asfalto per poi tornare sul percorso sterrato. Quello che non era prevista era l\u2019uscita di strada di una auto che qualche giorno prima aveva tirato dritta una curva finendo per ribaltarsi pi\u00f9 volte e rovinando proprio su uno dei percorsi: oggetti ancora integri, scatoe di cartone non umide tradiscono il fatto che l\u2019evento \u00e8 stato recente. Non riusciamo ad immaginare dinamica, eventuali turisti coinvolti, operazioni di recupero: perch\u00e9 diavolo il rottame \u00e8 ancora l\u00ec?<\/p>\n<p><b>Il pezzo forte della vallata sono le 3 sorelle<\/b>, 3 rocce che la leggenda narra siano in realt\u00e0 3 principesse tramutate in montagne affinch\u00e9 non fossero insediate: i percorsi corrono lungo i costoni, su pi\u00f9 livelli e si intersecano in pi\u00f9 punti, ora diretti verso cascate, ora verso <b>punti panoramici, ora verso vertiginose e numerose scale<\/b> che tagliano la montagna abbreviando la strada. I percorsi in generale sono scarsamente segnalati e piuttosto pericolosi almeno a mio parere: parapetti bassi, scale di metallo scivolose con umidit\u00e0, scarsi cartelli segnaletici ed innumerevoli bivi che guidano al dubbio.<\/p>\n<p>Nulla di impossibile ma in un posto che vive di fatto di questi percorsi ci si aspetta una cura migliore di mappe, segnaletiche e parapetti, soprattutto nei punti panoramici pi\u00f9 ambiti dove insiste, fra l\u2019altro, un vento forte capace di spostare a tratti cose e di sbilanciare persone.<\/p>\n<p>Freddo, vento ed un po di pioggia pi\u00f9 il timore che <b>Port Stephens <\/b>poi non fosse cos\u00ec come speravamo circa avvistamento di delfini e balene ci hanno spinti a rimanere qui un giorno in pi\u00f9, a rinunciare al mare ed a dedicarci alla montana di giorno, a serate di caff\u00e8 e biscotti ed a cene in quella che una volta era la vecchia banca e che oggi \u00e8 un locale a met\u00e0 fra pub e ristorante frequentato da gente del posto, da vecchine in libera uscita vestite stile country e da giovanotti che paiono usciti dalla penna di uno sceneggiatore che vive di stereotipi a tema campagna americana.<\/p>\n<p><b>Anche qui la vita scorre lenta ed ospitale,<\/b> il freddo si fa sentire ed i prezzi sono medio alti: questa Australia non \u00e8 quella del deserto ma non \u00e8 quella delle grandi citt\u00e0 e cos\u00ec la gente ci va a genio e ci piace fare la spesa al supermarket, fermarci con la macchina, caricarla, organizzare provviste per il pranzo di domani lungo il percorso, chiacchierare stanchi e soddisfatti dei paesaggi conquistati. Stiamo bene, siamo sereni, camminiamo una media di 10 km al giorno, che sia in citt\u00e0, nel deserto oppure sui monti. Che ci manca?<\/p>\n<p>Poter proseguire ancora un po&#8217;! Ma sappiamo accontentarci e so per certo che sapremo usare quanto visto ed imparato per un prossimo viaggio.<\/p>\n<p><b>Torniamo a Sydney cos\u00ec come fanno gli elefanti che se ne vanno lenti a morire in certi posti:<\/b> in citt\u00e0 spenderemo 2 giorni senza troppi programmi e lasceremo che il tempo si consumi pian piano, che cementi i nostri appunti, le nostre piccole scoperte, le immagini fotografate e quelle perse ma bene impresse in mente, come le balene con i loro sbuffi, i loro salti improvvisati proprio mentre spegni la macchina fotografica e dici qualcosa tipo: <i>\u201cce ne andiamo?\u201d\u00a0<\/i>Lasceremo che tutto maturi ancora, che fermenti, poi, che si cementi infine.<\/p>\n<p><b>Il viaggio si \u00e8 di fatto concluso, l\u2019impresa \u00e8 riuscita, <\/b>la conquista avvenuta: nel suo piccolo anche questo \u00e8 un viaggio con la sua epica, con i suoi aneddoti, qualche bisticcio organizzativo, qualche pasticcio inavvertito, tante citt\u00e0 ed ancor pi\u00f9 km.<\/p>\n<p>Sento che abbiamo portato via un bagaglio pi\u00f9 pesante e che questo \u00e8 vero anche non solo in senso metaforico visto che eravamo partiti senza tende, sacco a pelo e materassini e che ora, invece, tutto questo \u00e8 inzeppato fra zaino ed un ulteriore bagaglio a mano che satura la cappelliera sotto la quale sto scrivendo ora.<\/p>\n<p><b>Cosa manca? Mi pare nulla, gli ingredienti ci sono stati tutti e tutti sono stati amalgamati cos\u00ec che il sapore sia pieno e soddisfacente, cos\u00ec che occhi, naso e bocca siano stati sfamati a sufficienza<\/b>. C\u2019\u00e8 tutto, non manca nulla, compresi quei momenti di vuoto e di \u201c<i>che facciamo ora?<\/i>\u201d vissuti nelle ultime ore quando sei in citt\u00e0 ed aspetti di andare in aeroporto, quando ormai il bagaglio \u00e8 in reception e tu bivacchi sulle panchine di un parco, in una caffetteria oppure al sole di un muretto aspettando non si sa mai bene cosa.<\/p>\n<p><b>Quegli attimi di noia inconcludente, di vuoto, di dubbio sul da farsi, quei momenti in cui ti chiedi perch\u00e9 cazzo mai finisci sempre per non organizzare al meglio le operazioni di rientro ed i tempi relativi forse sono il gusto ulteriore del viaggio in senso lato.\u00a0<\/b><\/p>\n<p>Un gusto che spero di non dimenticare mai e del quale so che non vorr\u00f2 fare a meno: il ritorno a casa.<\/p>\n<p><b>Perch\u00e9 \u00e8 il ritorno che da senso al viaggio, ne sono ancora certo.\u00a0<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le montagne blue\u00a0non sono blue cos\u00ec come i 12 apostoli non sono in realt\u00e0 12: i veri romanzi stanno scritti nelle guide turistiche, ne sono ormai certo.\u00a0Il mostro che dentro ci ha divorato nella lenta Sydney ci ha spinto a lasciarla in fretta per via di quelle riflessioni che giorni fa abbiamo fatto bevendo un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,1810],"tags":[1824,1887,1886,1885,1884,1881,1831,1888],"_links":{"self":[{"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/posts\/3099"}],"collection":[{"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/comments?post=3099"}],"version-history":[{"count":4,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/posts\/3099\/revisions"}],"predecessor-version":[{"id":3103,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/posts\/3099\/revisions\/3103"}],"wp:attachment":[{"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/media?parent=3099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/categories?post=3099"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/tags?post=3099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}