{"id":707,"date":"2012-08-29T19:25:27","date_gmt":"2012-08-29T17:25:27","guid":{"rendered":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/?p=707"},"modified":"2013-07-18T14:23:01","modified_gmt":"2013-07-18T12:23:01","slug":"sentire-varanasi","status":"publish","type":"post","link":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/2012\/08\/29\/sentire-varanasi\/","title":{"rendered":"Sentire Varanasi"},"content":{"rendered":"<p><a href=\"http:\/\/www.mynirvana.it\/ilcircodelleparole\/wp-content\/uploads\/2012\/08\/20120829-225331.jpg\"><img decoding=\"async\" class=\"alignnone size-full\" alt=\"20120829-225331.jpg\" src=\"http:\/\/www.mynirvana.it\/ilcircodelleparole\/wp-content\/uploads\/2012\/08\/20120829-225331.jpg\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">&#8220;<strong>Varanasi<\/strong> <strong>\u00e8 una citt\u00e0 che non devi vedere ma devi sentire<\/strong>&#8221;<br \/>\n\u00c8 questa la frase del nostro guidatore mentre assonati e determinati ci muoviamo verso il ghat con lo sgangherato tuk tuk.<\/p>\n<p style=\"text-align: justify;\">Il ghat scelto \u00e8 poco frequentato ed alle prime luci dell&#8217;alba incontriamo pochi indiani che si recano l\u00ec ordinatamente ed in silenzio per le abluzioni del mattino.<br \/>\n<strong>I vicoli sono stretti e molto sporchi<\/strong>, orientarsi \u00e8 una impresa disperata ma siamo riusciti a contrattare ed ottenere un guidatore di tuk tuk che ci aiuta a muoverci nelle prime ore del mattino.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Il prezzo di 300 rupie ( circa 4 euro) \u00e8 ottimo. Lui sembra un buon uomo e siamo pi\u00f9 felici di averlo scelto quando partendo dal parcheggio davanti l&#8217;hotel \u00e8 stato preso in giro per un difetto al labbro superiore ( labbro leporino): le risate cattive dei suoi colleghi fanno a pugni con la sua estrema decenza e disponibilit\u00e0, con l&#8217;ordine impeccabile dei suoi baffi, lasciati credo anche per mascherare il difetto, ed i capelli, di certo opera dei barbieri che lavorano in strada.<\/p>\n<p style=\"text-align: justify;\">Nel labirinto dei vicoli incontriamo asini, <strong>centinaia di<\/strong> <strong>cani malati<\/strong>, <strong>scimmie e bambini intenti a rovistare nei rifiuti dividendo il cibo con le mucche.<\/strong><br \/>\nLe mucche non muovono che pochi passi e <strong>sono sempre in silenzio<\/strong> anche nei momenti di disordine stradale pi\u00f9 ossessivo.<br \/>\nMi stupisce la loro condotta, il pensare che i nostri animali, in Italia, al minimo colpo di clacson reagiscono con aggressivit\u00e0.<br \/>\n<strong>\u00c9 vero, ci si abitua a tutto quindi.<\/strong><br \/>\n<strong>Le mucche masticano lente il cibo avariato<\/strong> che trovano in terra: <strong>lo scarto di uno scarto<\/strong>: spesso vomitano loro stesse e l&#8217;odore di urina e marciume ci accompagna ovunque.<br \/>\nI bambini sono nudi e scalzi, sorridono col<strong> viso tondo che sovrasta il monte della loro pancia piuttosto gonfia<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Sono gli ultimi, gli <strong>intoccabili<\/strong>, fanno parte della casta pi\u00f9 bassa e devono accettarlo, cos\u00ec come hanno dovuto e voluto i loro genitori.<\/p>\n<p style=\"text-align: justify;\">Ci sono persone sdraiate in terra, abbandonate e <strong>forse morte<\/strong>, <strong>altre respirano lente,<\/strong> nascoste da folte barbe e vestiti cementati sulla carne causa sporco.<br \/>\n<strong>La faccia nella polvere: immobili spettatori, forse suppellettili di quella scena che rasenta la negazione della ragione.<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;India \u00e8 un paese verde, potrebbero vivere in molte zone: agricoltura, semplice, come nella motte dei tempi; potrebbero sollevarsi, organizzarsi pur rimanendo al netto di meccanizzazioni costose, del progresso tecnologico.<br \/>\nMa le caste e la religione sono la legge e gli intoccabili vivono cos\u00ec: non costretti, per scelta.<\/p>\n<p style=\"text-align: justify;\">Stamattina ho aperto gli occhi pensando alla <strong>domanda<\/strong> con la quale Manu si \u00e8 addormentata ieri notte: gli indiani vivono cos\u00ec a &#8220;causa&#8221; della loro religione oppure, vivendo in questo modo per il poco avere e la poca organizzazione sociale, hanno scelto, creato, una religione di questo tipo ?<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c8 piuttosto difficile da spiegare la sottile domanda cos\u00ec come il riuscire a darsi una spiegazione<\/strong>. L&#8217;istinto mi dice che la religione sia la spiegazione per le condizioni di vita, che come in ogni altro caso la religione \u00e8 fatta di dogmi che intendono giustificare fatti, ma \u00e8 una spiegazione semplicistica: di base la loro condizione \u00e8 migliorabile, e sensibilmente, agendo in prima persona senza dover aspettare governo o politicanti in generale. Pulire la strada, evitare di fare i bisogni ovunque, mangiare le mucche oppure coltivare almeno la terra.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec continuo a camminare pensandoci su e mentre evito lo sterco in terra, <strong>i cani che barcollano affamati ed imbestiati dalla rabbia<\/strong>, idealizzo un paese differente con poco sforzo.<\/p>\n<p style=\"text-align: justify;\">Spero che le mie foto abbiamo saputo catture gli attimi che sto cercando di descrivere e quelle sensazioni che ora mi sembrano cos\u00ec intime da non trovare posto qui ( spero di riuscire presto a pubblicarne qualcuna).<br \/>\nAveva ragione il guidatore:<strong> feel, not see.<\/strong><\/p>\n<p style=\"text-align: justify;\">Affittiamo <strong>una piccola barca a motore<\/strong> (da preferire a quelle a remi per via della corrente e del fiume molto alto)<strong> per poter discendere e risalire un buon tratto del piccolo golfo.<\/strong><br \/>\nAlcuni hindu sono immersi per met\u00e0 corpo in acqua e bevono sciacquandosi la bocca, altri si lavano i denti alla meglio, con le mani, mentre altri gettano fiori o si versano acqua in testa per ingraziarsi le divinit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Ci sono capre sui gradoni, <strong>scimmie che controllano la situazione urlando <\/strong>ogni tanto dall&#8217;alto, santoni con capelli annodati e lunghissimi, visi dipinti e tanto silenzio umano da riuscire a metterci a disagio.<br \/>\nIl ragazzo della barca parla bene inglese e navigando ci spiega degli edifici di fronte. Il palazzo delle vedove , il tempio di Shiva, il tempio delle scimmie ( attenzione, mordono ed aggrediscono !)<br \/>\nNon ci sono barche in acqua e siamo solo noi 4 con i due marinai improvvisati.<br \/>\n<strong><br \/>\nUn acqua oleosa e marrone scorre sotto di noi<\/strong>; fa impressione la sacralit\u00e0 che rappresenta per gli hindu e come questa stessa fosse un pericolo solo per noi. Temiamo gli schizzi di acqua, le zanzare ( quelle sul fiume sono veramente tante e, per forza di cose, temibili&#8230;).<br \/>\n<strong>Ci sosteniamo, organizzati, seduti due su un lato e due sull&#8217;altro per equilibrare la navigazione ed evitare sciabordii.<\/strong><br \/>\nScattiamo foto alla meglio ma per la maggior parte del tempo <strong>osserviamo senza confrontarci,<\/strong> ingerendo le spiegazioni che ci danno, domandando ma senza commentare fra di noi.<br \/>\n<strong>Capire per poi metabolizzare. Forse.<\/strong><\/p>\n<p style=\"text-align: justify;\">I forni <strong>crematori<\/strong> sono 2 : uno elettrico per i pi\u00f9 poveri ed uno a legna per i pi\u00f9 ricchi. I forni sono accesi incessantemente da centinaia di anni, ci dicono, ed esiste anche il metodo di cremazione classico, fuori dai forni, sulle rive del fiume.<br \/>\nVengono cremati tutti gli Induisti fatta eccezione per <strong>i bambini sotto i 10 anni, le donne incinta, i morti per morso di cobra<\/strong> ed una categoria che non mi perdono di non aver capito.<br \/>\n<strong>Questi esclusi dal rito funerario della cremazione vengono gettati nel fiume con pietre appese al corpo<\/strong> cos\u00ec che possano affondare e che i pesci possano mangiarli.<br \/>\nIl problema \u00e8 che le acque sono cos\u00ec inquinate ed infette che <strong>non ci sono pesci,<\/strong> ma loro questo lo negano o forse non lo capiscono.<\/p>\n<p style=\"text-align: justify;\">Fatto sta che i cadaveri perdono le pietre <strong>perch\u00e9 putrefacendo si gonfiano.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>La conseguenza \u00e8 che tornano a galla trasportati dalla corrente: un corpo senza viso, vestiti, ne storia, sfiora la nostra barca.<\/strong><br \/>\n<strong> \u00c8 come se nuotasse lento, se fosse immerso a cercare qualcosa in acqua, forse una spiegazione.<\/strong><br \/>\nBianco e gonfio, <strong>con le ossa evidenti dalla pelle sottile<\/strong>.<br \/>\nNessuno di noi volta lo sguardo ma <strong>nessuno scatta fotografie<\/strong>.<br \/>\nDurante la cena di ieri ci siamo confrontati sul nostro <strong>codice etico di viaggiatori\/turisti<\/strong>: ovviamente rispettiamo il posto e la religione e le nostre macchine digitali non cattureranno per scelta alcuni momenti.<\/p>\n<p style=\"text-align: justify;\">Scesi dalla piccola imbarcazione la citt\u00e0 sembra accoglierci in maniera meno violenta. Giriamo fra i vicoli diretti al crematorio. Ho chiesto di accompagnarci fra i vicoli umidi, Edu \u00e8 in silenzio e lascia a me il colloquio con l&#8217;improvvisata guida e la testa delle piccola spedizione.<br \/>\n<strong>Cataste di legna<\/strong> occupano le uniche porzioni ordinate del quartiere. Il legno per le pire va pesato, scelto in base alla sua qualit\u00e0 ed influisce sul costo del rito. <strong>A volte la pira non basta a bruciare il defunto<\/strong> e cos\u00ec accade l&#8217;irreparabile con le igieniche conseguenze del caso: <strong>parti incombuste dei corpi sono l\u00ec fra la strada ed il fiume<\/strong> ma noi non ne vediamo. Ci dir\u00e0 un tedesco incontrato pi\u00f9 avanti di aver visto chiaramente una gamba mimetizzata fra rifiuti e feci degli animali.<\/p>\n<p style=\"text-align: justify;\"><strong>Silenziosi operai accatastano legna<\/strong> <strong>preparando una pira che da l\u00ec a qualche ora brucer\u00e0 una storia che non sapremo<\/strong>, una faccia, delle idee, un uomo che ormai sar\u00e0 come svuotato e reso quasi oggetto insensato.<br \/>\nUn odore dolciastro invade l&#8217;aria e domina il puzzo di poco prima. I formi lavorano religiosamente cos\u00ec come gli operai della morte.<br \/>\nNon ci sono che sparuti ed impressionati turisti : <strong>molti visitano Varanasi ma pochi si spingono qui.<\/strong><\/p>\n<p style=\"text-align: justify;\">Le scene, sono certo, hanno segnato come previsto ogni spettatore: non \u00e8 per un gusto macabro ma si \u00e8 trascinati l\u00ec, si diventa come desiderosi ed affamati di vedere per capire meglio, per trovare una spiegazione a quella che per la nostra cultura sfiora il concetto di &#8220;violenza&#8221;.<br \/>\nQualcuno, e fa male, <strong>si comporta da cieco turista<\/strong>: un orientale che non riusciamo a capire da dove venga precisamente si immerge nel Gange ridendo, scherzando, mescolandosi e facendosi fotografare, ignaro di pericoli e del senso del tutto per gli indiani che, non afferrano l&#8217;orrore di quel comportamento e cercano di coinvolgerloconvinti sia convertito all&#8217;induismo.<\/p>\n<p style=\"text-align: justify;\">E fa persino strano poi tornare in albergo per le operazioni di ogni giorno: colazione, bagagli, un giro in quello che chiamano centro citt\u00e0: non c&#8217;\u00e8 tristezza ma \u00e8 <strong>chiarissima l&#8217;idea di qualcosa che somiglia ad una saziet\u00e0<\/strong> alla quale la colazione organizzata in albergo non ha contribuito.<\/p>\n<p>Massimo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Varanasi \u00e8 una citt\u00e0 che non devi vedere ma devi sentire&#8221; \u00c8 questa la frase del nostro guidatore mentre assonati e determinati ci muoviamo verso il ghat con lo sgangherato tuk tuk. Il ghat scelto \u00e8 poco frequentato ed alle prime luci dell&#8217;alba incontriamo pochi indiani che si recano l\u00ec ordinatamente ed in silenzio per [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":710,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,732],"tags":[372,379,376,378,373,10,374,380,375,377,366,349],"_links":{"self":[{"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/posts\/707"}],"collection":[{"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/comments?post=707"}],"version-history":[{"count":10,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/posts\/707\/revisions"}],"predecessor-version":[{"id":844,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/posts\/707\/revisions\/844"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/media\/710"}],"wp:attachment":[{"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/media?parent=707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/categories?post=707"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mynirvana.it\/ilcircodelleparole\/index.php\/wp-json\/wp\/v2\/tags?post=707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}